{"id":262,"date":"2026-03-04T21:35:25","date_gmt":"2026-03-04T21:35:25","guid":{"rendered":"https:\/\/nonoresto.be\/business\/matto-2\/"},"modified":"2026-03-04T21:35:25","modified_gmt":"2026-03-04T21:35:25","slug":"matto","status":"publish","type":"business","link":"https:\/\/nonoresto.be\/fr\/restaurant\/matto\/","title":{"rendered":"MATTO"},"content":{"rendered":"<p>MATTO est un restaurant italien intimiste o\u00f9 le <b>menu<\/b> d\u00e9gustation, ax\u00e9 sur le partage, est \u00e0 l&rsquo;honneur et o\u00f9 l&rsquo;exp\u00e9rience compte autant que le plat lui-m\u00eame. Les convives sont accueillis dans une demeure de ma\u00eetre o\u00f9 l&rsquo;on sonne \u00e0 la porte, ce qui instaure d&#8217;embl\u00e9e un climat de discr\u00e9tion et d&rsquo;exclusivit\u00e9, sans pour autant tomber dans la formalit\u00e9 ou la froideur. Le concept s&rsquo;adresse clairement \u00e0 ceux qui appr\u00e9cient un repas pris sur le pouce, le partage de plats et la d\u00e9couverte culinaire, plut\u00f4t qu&rsquo;aux repas rapides ou aux classiques plats \u00e0 la carte.<\/p>\n<h2> Concept : Le partage \u00e0 l&rsquo;italienne avec carte blanche<\/h2>\n<p> Chez MATTO, le concept repose sur un menu d\u00e9gustation \u00e0 la carte, compos\u00e9 de plusieurs plats \u00e0 partager \u00e0 table et r\u00e9guli\u00e8rement renouvel\u00e9 au gr\u00e9 des saisons et des produits du march\u00e9. Plut\u00f4t qu&rsquo;un menu interminable, vous choisissez un plat fixe, ce qui, pour beaucoup, est synonyme de s\u00e9r\u00e9nit\u00e9\u00a0: vous laissez le chef d\u00e9cider et vous vous concentrez sur l&rsquo;exp\u00e9rience. Ceux qui recherchent une <b>pizzeria<\/b> italienne traditionnelle avec des pizzas et des p\u00e2tes classiques ne trouveront pas leur bonheur ici, car la cuisine s&rsquo;apparente clairement \u00e0 un bistro moderne avec une touche italienne.<\/p>\n<p> Les plats sont g\u00e9n\u00e9ralement dispos\u00e9s au centre de la table, invitant les convives \u00e0 go\u00fbter et \u00e0 partager, ce qui est id\u00e9al pour les couples ou les petits groupes qui aiment d\u00e9couvrir diff\u00e9rentes saveurs. Les clients appr\u00e9cient la vari\u00e9t\u00e9 des plats propos\u00e9s : poisson, viande et v\u00e9g\u00e9tariens. Toutefois, l&rsquo;absence de choix individuels peut surprendre au premier abord. Ce restaurant s&rsquo;adresse donc principalement aux gourmets curieux, ouverts \u00e0 un menu fixe plut\u00f4t qu&rsquo;\u00e0 une carte traditionnelle.<\/p>\n<h2> Exp\u00e9rience culinaire et gustative<\/h2>\n<p> La cuisine de MATTO est souvent d\u00e9crite comme raffin\u00e9e, \u00e9quilibr\u00e9e et r\u00e9confortante, avec des influences italiennes \u00e9videntes, mais sans tomber dans les clich\u00e9s. Parmi les exemples cit\u00e9s par les habitu\u00e9s figurent de succulentes boulettes de viande aux olives et \u00e0 la provola fum\u00e9e, des joues de porc longuement confites accompagn\u00e9es de c\u00e9leri-rave cr\u00e9meux, et des plats de l\u00e9gumes o\u00f9 les textures et les saveurs sont savamment travaill\u00e9es. Cette approche s&rsquo;inscrit dans la tendance de <b>la gastronomie<\/b> italienne moderne, o\u00f9 la simplicit\u00e9 et la qualit\u00e9 des produits sont primordiales, tandis que la pr\u00e9sentation et les techniques sont contemporaines.<\/p>\n<p> Autre caract\u00e9ristique typique de MATTO\u00a0: le r\u00f4le de la \u00ab\u00a0painza\u00a0\u00bb\u00a0: une galette ovale et a\u00e9r\u00e9e \u00e0 base de levain, l\u00e9g\u00e8rement garnie, croustillante sur les bords et moelleuse \u00e0 l\u2019int\u00e9rieur, \u00e0 mi-chemin entre le pain et la focaccia. Elle sert de support \u00e0 des ingr\u00e9dients comme le poulpe, la passata de tomates et les olives, et constitue souvent un \u00e9l\u00e9ment important du repas. Les clients appr\u00e9cient les associations de saveurs r\u00e9fl\u00e9chies et savoureuses, m\u00eame si certains trouvent le style plus d\u00e9licat que franchement prononc\u00e9. De ce fait, ceux qui recherchent des saveurs robustes et intenses pourraient trouver les plats un peu trop subtils ou \u00ab\u00a0trop chics\u00a0\u00bb pour un restaurant italien.<\/p>\n<h3> Points positifs de la cuisine<\/h3>\n<ul>\n<li> Les plats sont souvent lou\u00e9s pour leur \u00e9quilibre, leur raffinement et leur c\u00f4t\u00e9 r\u00e9confortant, avec une grande attention port\u00e9e \u00e0 la texture et \u00e0 la finition.<\/li>\n<li> Le menu carte blanche offre un bon aper\u00e7u des possibilit\u00e9s de la cuisine et fait d\u00e9couvrir aux clients des combinaisons qu&rsquo;ils n&rsquo;auraient peut-\u00eatre pas command\u00e9es autrement.<\/li>\n<li> Une attention particuli\u00e8re est port\u00e9e aux options v\u00e9g\u00e9tariennes et aux produits de saison, ce qui correspond \u00e0 une fa\u00e7on plus responsable de consommer au restaurant.<\/li>\n<\/ul>\n<p> Pour ceux qui appr\u00e9cient un d\u00eener complet et raffin\u00e9, la cuisine de MATTO se pr\u00e9sente comme un tout harmonieux. Ici, point de grandes portions de p\u00e2tes ou de pizzas individuelles, mais des plats \u00e0 partager soigneusement compos\u00e9s qui, ensemble, racontent une histoire.<\/p>\n<h3> Points faibles selon les clients<\/h3>\n<ul>\n<li> Les portions ne sont pas per\u00e7ues comme aussi g\u00e9n\u00e9reuses par tous\u00a0: certains visiteurs les trouvent plut\u00f4t modestes, surtout compte tenu du raffinement du restaurant et du prix.<\/li>\n<li> Certaines pr\u00e9parations sont per\u00e7ues comme trop a\u00e9riennes ou \u00ab semblables \u00e0 de la mousseline \u00bb, ce qui emp\u00eache les gens de profiter d&rsquo;un style italien plus familial et copieux.<\/li>\n<li> Le concept de partage fixe et le choix limit\u00e9 peuvent \u00eatre moins attrayants pour ceux qui aiment choisir exactement ce qu&rsquo;ils mangent.<\/li>\n<\/ul>\n<p> Quiconque envisage de d\u00eener chez MATTO doit savoir qu&rsquo;il s&rsquo;agit davantage d&rsquo;une exp\u00e9rience culinaire que d&rsquo;une <b>trattoria<\/b> italienne classique o\u00f9 l&rsquo;on commande rapidement une grande assiette de p\u00e2tes. L&rsquo;accent est mis sur le partage, la d\u00e9gustation et le fait de prendre son temps, ce qui est un atout pour beaucoup, mais moins id\u00e9al pour d&rsquo;autres.<\/p>\n<h2> Boissons, vins et cocktails<\/h2>\n<p> C\u00f4t\u00e9 boissons, la carte des cocktails cr\u00e9atifs est particuli\u00e8rement remarquable. Les clients appr\u00e9cient les combinaisons originales qui sortent de l&rsquo;ordinaire et proposent des recettes qui s&rsquo;accordent \u00e0 merveille avec les saveurs des plats. Pour les amateurs d&rsquo;ap\u00e9ritif ou d&rsquo;accords mets-vins, cela pourrait \u00eatre un argument de poids pour r\u00e9server. La carte des vins, elle aussi, est r\u00e9guli\u00e8rement salu\u00e9e pour sa s\u00e9lection pointue, offrant des options qui subliment la cuisine italienne moderne.<\/p>\n<p> L&rsquo;accent mis sur les accords mets et vins, \u00e0 la mani\u00e8re <b>d&rsquo;un bar \u00e0 vins,<\/b> s\u00e9duit les clients d\u00e9sireux de prolonger leur soir\u00e9e par un ap\u00e9ritif, un d\u00eener et, \u00e9ventuellement, un digestif, le tout dans une ambiance harmonieuse. Cependant, ceux qui recherchent avant tout un simple vin de la maison et un plat principal rapide pourraient \u00eatre tent\u00e9s de payer plus cher pour le cadre et la cr\u00e9ativit\u00e9 que n\u00e9cessaire. N\u00e9anmoins, pour ceux qui privil\u00e9gient une soir\u00e9e gastronomique avec des boissons de qualit\u00e9, le rapport qualit\u00e9-prix s&rsquo;av\u00e8re souvent excellent.<\/p>\n<h2> Ambiance et int\u00e9rieur<\/h2>\n<p> MATTO est install\u00e9 dans une maison de ville o\u00f9 l&rsquo;on sonne \u00e0 la porte puis on monte les escaliers, ce qui donne souvent l&rsquo;impression d&rsquo;une adresse secr\u00e8te. \u00c0 l&rsquo;int\u00e9rieur, des teintes de bleu profond, des moulures et des objets soigneusement s\u00e9lectionn\u00e9s dominent, conf\u00e9rant au lieu des allures de cabinet de curiosit\u00e9s. L&rsquo;\u00e9clairage est doux, les fauteuils confortables, et l&rsquo;espace est d\u00e9crit comme calme et pourtant vibrant, sans aucune agitation.<\/p>\n<p> Cette combinaison fait de MATTO un lieu id\u00e9al pour une soir\u00e9e romantique \u00e0 deux, mais aussi pour les petits groupes appr\u00e9ciant une ambiance intimiste. Certains clients trouvent l&rsquo;atmosph\u00e8re plus raffin\u00e9e que d\u00e9contract\u00e9e, notamment compar\u00e9e \u00e0 celle de son \u00e9tablissement jumeau, Ciccio, situ\u00e9 dans le m\u00eame b\u00e2timent, qui est plus informel et ax\u00e9 sur le bar. Ceux qui recherchent l&rsquo;ambiance d\u00e9contract\u00e9e d&rsquo;un <b>bistro<\/b> anim\u00e9 et dynamique pourraient trouver le calme un peu pesant, tandis que d&rsquo;autres y voient justement son plus grand atout.<\/p>\n<h2> Service et r\u00e9ception<\/h2>\n<p> Le service chez MATTO est unanimement salu\u00e9\u00a0: le personnel est d\u00e9crit comme chaleureux, attentionn\u00e9 et professionnel, tout en restant accessible. Les clients appr\u00e9cient les efforts d\u00e9ploy\u00e9s pour communiquer en plusieurs langues, dont le n\u00e9erlandais, ce qui facilite l\u2019acc\u00e8s \u00e0 l\u2019\u00e9tablissement. L\u2019\u00e9quipe explique g\u00e9n\u00e9ralement clairement le concept de partage et le menu, ce qui est particuli\u00e8rement appr\u00e9ciable pour les nouveaux clients.<\/p>\n<p> Le service est \u00e0 l&rsquo;image du reste du restaurant\u00a0: d\u00e9contract\u00e9 et personnalis\u00e9, loin d&rsquo;\u00eatre pr\u00e9cipit\u00e9 ou formel. On constate peu d&rsquo;attente ou de probl\u00e8mes d&rsquo;organisation\u00a0; la soir\u00e9e se d\u00e9roule g\u00e9n\u00e9ralement \u00e0 un rythme soutenu, ce qui est essentiel pour un repas \u00e0 plusieurs plats. Cependant, ceux qui privil\u00e9gient un repas rapide et efficace \u2013 par exemple, un d\u00e9jeuner d&rsquo;affaires express \u2013 seront moins s\u00e9duits, car MATTO est avant tout con\u00e7u pour un d\u00eener gastronomique.<\/p>\n<h2> Niveau de prix et rapport qualit\u00e9<\/h2>\n<p> Les avis situent le prix d&rsquo;un menu complet chez MATTO entre quarante et cinquante euros par personne, hors boissons. Ce menu est souvent consid\u00e9r\u00e9 comme d&rsquo;un prix raisonnable au regard de la qualit\u00e9 des ingr\u00e9dients, du cadre et du soin apport\u00e9 en cuisine. Dans le paysage gastronomique bruxellois, o\u00f9 les \u00e9tablissements italiens modernes proposant des produits de qualit\u00e9 sont g\u00e9n\u00e9ralement on\u00e9reux, MATTO est souvent per\u00e7u comme un choix judicieux pour ceux qui sont pr\u00eats \u00e0 investir un peu plus pour une exp\u00e9rience culinaire compl\u00e8te.<\/p>\n<p> Bien s\u00fbr, la perception des prix reste subjective\u00a0: les clients qui privil\u00e9gient les portions g\u00e9n\u00e9reuses ou les plats <b>de p\u00e2tes<\/b> classiques pourraient trouver que la pr\u00e9sentation raffin\u00e9e et l\u2019approche cr\u00e9ative ne correspondent pas tout \u00e0 fait \u00e0 leur d\u00e9finition personnelle du \u00ab\u00a0bon rapport qualit\u00e9-prix\u00a0\u00bb. \u00c0 l\u2019inverse, une autre client\u00e8le consid\u00e8re que la carte bien pens\u00e9e, l\u2019ambiance et le souci du d\u00e9tail justifient pleinement les prix. Il est donc important que les clients potentiels s\u2019attendent \u00e0 un restaurant italien contemporain qui privil\u00e9gie l\u2019exp\u00e9rience \u00e0 la quantit\u00e9.<\/p>\n<h2> \u00c0 qui MATTO convient-il ?<\/h2>\n<p> MATTO s&rsquo;adresse principalement aux gourmets appr\u00e9ciant un <b>d\u00eener<\/b> raffin\u00e9 et d\u00e9contract\u00e9 aux saveurs italiennes authentiques, avec un menu surprise. Les couples, les petits groupes d&rsquo;amis et les fins gourmets y trouveront leur compte, notamment s&rsquo;ils prennent le temps de savourer plusieurs plats et d&rsquo;essayer, pourquoi pas, des cocktails ou des accords mets et vins. Le restaurant est moins adapt\u00e9 aux familles avec de jeunes enfants ou aux groupes recherchant un repas rapide et informel avec un large choix et des portions g\u00e9n\u00e9reuses.<\/p>\n<p> Quiconque recherche une <b>exp\u00e9rience culinaire<\/b> italienne in\u00e9dite, avec des plats \u00e0 partager, des pains au levain cr\u00e9atifs et un cadre raffin\u00e9, trouvera son bonheur chez MATTO. Il est important de souligner que la cuisine ne se contente pas des classiques pizza et p\u00e2tes, mais propose une interpr\u00e9tation moderne des saveurs italiennes. Les clients potentiels, sensibles \u00e0 ce type d&rsquo;aventure gastronomique, d\u00e9couvriront ici un concept coh\u00e9rent, alliant points forts et subtilit\u00e9s qui contribuent \u00e0 une immersion authentique.<\/p>\n<h3> R\u00e9sum\u00e9 des avantages et des inconv\u00e9nients pour les clients<\/h3>\n<ul>\n<li> <strong>Points forts\u00a0:<\/strong> plats \u00e0 partager raffin\u00e9s, menu de saison, belle s\u00e9lection de cocktails et de vins, service chaleureux et int\u00e9rieur \u00e9l\u00e9gant et calme.<\/li>\n<li> <strong>Points n\u00e9gatifs\u00a0:<\/strong> formule fixe et choix limit\u00e9, portions jug\u00e9es modestes par certains, moins adapt\u00e9 \u00e0 ceux qui s\u2019attendent \u00e0 un restaurant italien classique avec pizzas et grandes assiettes de p\u00e2tes.<\/li>\n<\/ul>\n<p> Dans l&rsquo;ensemble, MATTO se pr\u00e9sente comme un restaurant italien contemporain qui privil\u00e9gie l&rsquo;ambiance, la cr\u00e9ativit\u00e9 et le partage plut\u00f4t que le volume et la rapidit\u00e9. Il est essentiel que les clients potentiels gardent cette caract\u00e9ristique \u00e0 l&rsquo;esprit lors de leur choix, afin que leur exp\u00e9rience au restaurant soit \u00e0 la hauteur de leurs attentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MATTO \u00e0 Ixelles est un restaurant italien intimiste proposant un menu \u00e0 partager, des cocktails cr\u00e9atifs et des plats raffin\u00e9s, id\u00e9al pour un d\u00eener tranquille ax\u00e9 sur le go\u00fbt et l&rsquo;ambiance.<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","business-categories":[26],"business-locations":[35,45],"business-countries":[24],"business_franchises":[172],"class_list":["post-262","business","type-business","status-publish","hentry","business_category-restaurant","business_location-brussel","business_location-elsene","business_country-be","business_franchises-matto"],"_links":{"self":[{"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/businesses\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/businesses"}],"about":[{"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/types\/business"}],"author":[{"embeddable":true,"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/businesses\/262\/revisions"}],"wp:attachment":[{"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"business_category","embeddable":true,"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/business-categories?post=262"},{"taxonomy":"business_location","embeddable":true,"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/business-locations?post=262"},{"taxonomy":"business_country","embeddable":true,"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/business-countries?post=262"},{"taxonomy":"business_franchises","embeddable":true,"href":"https:\/\/nonoresto.be\/fr\/wp-json\/wp\/v2\/business_franchises?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}